{"id":6628,"date":"2025-04-22T07:51:10","date_gmt":"2025-04-22T04:21:10","guid":{"rendered":"https:\/\/actobit.com\/actomag\/?p=6628"},"modified":"2025-04-22T07:51:10","modified_gmt":"2025-04-22T04:21:10","slug":"haproxy-as-a-reverse-proxy-on-pfsense","status":"publish","type":"post","link":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/","title":{"rendered":"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc"},"content":{"rendered":"<p style=\"text-align: justify;\">\u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u06cc\u06a9\u06cc \u0627\u0632 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631\u06cc\u0646 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u200c\u0628\u0627\u0632 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0634\u0628\u06a9\u0647 \u0648 \u0627\u0645\u0646\u06cc\u062a \u062f\u0631 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0648 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u067e\u0644\u062a\u0641\u0631\u0645 \u06a9\u0647 \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0633\u06cc\u0633\u062a\u0645\u200c\u0639\u0627\u0645\u0644 FreeBSD \u062a\u0648\u0633\u0639\u0647 \u06cc\u0627\u0641\u062a\u0647\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u0634 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0645\u0633\u06cc\u0631\u06cc\u0627\u0628\u06cc\u060c VPN \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0634\u0628\u06a9\u0647\u060c \u0628\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u062d\u0628\u0648\u0628 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. pfSense \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0639\u0645\u0627\u0644 \u0642\u0648\u0627\u0646\u06cc\u0646 \u0627\u0645\u0646\u06cc\u062a\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0628\u0644\u06a9\u0647 \u0628\u0627 \u0631\u0627\u0628\u0637 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0648\u0628\u200c\u0645\u062d\u0648\u0631 \u062e\u0648\u062f\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0634\u0628\u06a9\u0647 \u0631\u0627 \u0633\u0627\u062f\u0647\u200c\u062a\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u0627\u0636\u0627\u0641\u06cc\u060c \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0641\u0631\u0627\u062a\u0631 \u0627\u0632 \u06cc\u06a9 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 \u0645\u0639\u0645\u0648\u0644\u06cc \u06af\u0633\u062a\u0631\u0634 \u062f\u0627\u062f\u0647 \u0648 \u0628\u0647 \u0627\u0628\u0632\u0627\u0631\u06cc \u062c\u0627\u0645\u0639 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u200c\u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u060c HAProxy \u0627\u0633\u062a \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u067e\u06cc\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc pfSense \u062f\u0631 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 <a href=\"https:\/\/actobit.com\/services\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa-%d8%af%d9%88%d8%a7%d9%be%d8%b3\/\">\u062e\u062f\u0645\u0627\u062a \u062f\u0648\u0627\u067e\u0633<\/a> \u0648 \u0627\u062f\u063a\u0627\u0645 \u0628\u0627 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0634\u0628\u06a9\u0647\u060c \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u0645\u0642\u06cc\u0627\u0633\u200c\u067e\u0630\u06cc\u0631 \u0648 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">HAProxy\u060c \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0628\u0648\u0628\u200c\u062a\u0631\u06cc\u0646 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u062a\u0646\u200c\u0628\u0627\u0632 \u0628\u0631\u0627\u06cc \u0645\u062a\u0639\u0627\u062f\u0644\u200c\u0633\u0627\u0632\u06cc \u0628\u0627\u0631 (Load Balancing) \u0648 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633\u060c \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0631 \u0628\u0647\u06cc\u0646\u0647\u200c\u0633\u0627\u0632\u06cc \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0627\u06cc\u0641\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631 \u0628\u0627 \u0647\u062f\u0627\u06cc\u062a \u062f\u0631\u062e\u0648\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u0648\u0631\u0648\u062f\u06cc \u0628\u0647 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628\u060c \u0639\u0645\u0644\u06a9\u0631\u062f \u0648 \u0642\u0627\u0628\u0644\u06cc\u062a \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc\u200c\u0628\u062e\u0634\u062f. HAProxy \u0628\u0647 \u062f\u0644\u06cc\u0644 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0628\u0627\u0644\u0627\u060c \u0645\u0635\u0631\u0641 \u0645\u0646\u0627\u0628\u0639 \u06a9\u0645 \u0648 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u0627\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u062f\u06cc\u0631\u06cc\u062a SSL\u060c \u0628\u0631\u0631\u0633\u06cc \u0633\u0644\u0627\u0645\u062a \u0633\u0631\u0648\u0631\u0647\u0627 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u067e\u0631\u0648\u062a\u06a9\u0644\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u0648\u0639\u060c \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u06cc \u0645\u0648\u0631\u062f \u062a\u0648\u062c\u0647 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a. \u062f\u0631 pfSense\u060c \u0627\u062f\u063a\u0627\u0645 HAProxy \u0628\u0647 \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0633\u062e\u062a\u200c\u0627\u0641\u0632\u0627\u0631 \u06cc\u0627 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631 \u0627\u0636\u0627\u0641\u06cc\u060c \u06cc\u06a9 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u06a9\u0627\u0631\u0622\u0645\u062f \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u067e\u06cc\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u0628\u0631\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u0645\u062a\u0639\u062f\u062f\u06cc \u0645\u0627\u0646\u0646\u062f \u0648\u0628\u200c\u0633\u0631\u0648\u0631\u0647\u0627\u060c \u067e\u0627\u06cc\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0627\u062f\u0647 \u06cc\u0627 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u0627\u062e\u0644\u06cc \u0631\u0627 \u0645\u06cc\u0632\u0628\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u0627\u0633\u062a. \u062a\u0631\u06a9\u06cc\u0628 pfSense \u0648 HAProxy \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0627\u0645\u0646\u06cc\u062a \u0648 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0634\u0628\u06a9\u0647 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0628\u0644\u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u062a\u0645\u0631\u06a9\u0632 \u0648 \u0633\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u200c\u0647\u0627\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0631\u0627 \u0646\u06cc\u0632 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0645\u0631\u0627\u062d\u0644 \u062f\u0642\u06cc\u0642 \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u062f\u0631 pfSense \u0648 \u0686\u06af\u0648\u0646\u06af\u06cc \u0628\u0647\u0631\u0647\u200c\u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0622\u0646 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_73 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%DA%86%D8%B1%D8%A7_HAProxy_%D8%B1%D8%A7_%D8%B1%D9%88%DB%8C_pfSense_%D8%B1%D8%A7%D9%87_%D8%A7%D9%86%D8%AF%D8%A7%D8%B2%DB%8C_%DA%A9%D9%86%DB%8C%D9%85%D8%9F\" title=\"\u0686\u0631\u0627 HAProxy \u0631\u0627 \u0631\u0648\u06cc pfSense \u0631\u0627\u0647 \u0627\u0646\u062f\u0627\u0632\u06cc \u06a9\u0646\u06cc\u0645\u061f\">\u0686\u0631\u0627 HAProxy \u0631\u0627 \u0631\u0648\u06cc pfSense \u0631\u0627\u0647 \u0627\u0646\u062f\u0627\u0632\u06cc \u06a9\u0646\u06cc\u0645\u061f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%88%DB%8C%DA%98%DA%AF%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C_HAProxy_%D9%88_%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D8%A2%D9%86%E2%80%8C%D9%87%D8%A7\" title=\"\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc HAProxy \u0648 \u0627\u0647\u0645\u06cc\u062a \u0622\u0646\u200c\u0647\u0627\">\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc HAProxy \u0648 \u0627\u0647\u0645\u06cc\u062a \u0622\u0646\u200c\u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%AA%D8%AC%D9%85%DB%8C%D8%B9_%D9%81%D8%A7%DB%8C%D8%B1%D9%88%D8%A7%D9%84%D8%8C_%D8%B1%D9%88%D8%AA%D8%B1_%D9%88_%D9%BE%D8%B1%D8%A7%DA%A9%D8%B3%DB%8C_%D9%85%D8%B9%DA%A9%D9%88%D8%B3_%D8%AF%D8%B1_%DB%8C%DA%A9_%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87\" title=\"\u0645\u0632\u0627\u06cc\u0627\u06cc \u062a\u062c\u0645\u06cc\u0639 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0631\u0648\u062a\u0631 \u0648 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u062f\u0631 \u06cc\u06a9 \u062f\u0633\u062a\u06af\u0627\u0647\">\u0645\u0632\u0627\u06cc\u0627\u06cc \u062a\u062c\u0645\u06cc\u0639 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0631\u0648\u062a\u0631 \u0648 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u062f\u0631 \u06cc\u06a9 \u062f\u0633\u062a\u06af\u0627\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF%D9%87%D8%A7%DB%8C_%D8%B9%D9%85%D9%84%DB%8C_HAProxy_%D8%B1%D9%88%DB%8C_pfSense\" title=\"\u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc HAProxy \u0631\u0648\u06cc pfSense\">\u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc HAProxy \u0631\u0648\u06cc pfSense<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%A7%D8%AD%D9%84_%D9%86%D8%B5%D8%A8_%D9%88_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C_HAProxy_%D8%AF%D8%B1_%D9%81%D8%A7%DB%8C%D8%B1%D9%88%D8%A7%D9%84_pfSense\" title=\"\u0645\u0631\u0627\u062d\u0644 \u0646\u0635\u0628 \u0648 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc HAProxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense\">\u0645\u0631\u0627\u062d\u0644 \u0646\u0635\u0628 \u0648 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc HAProxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B1_%D9%86%D8%B5%D8%A8_%D8%A8%D8%B3%D8%AA%D9%87_HAProxy\" title=\"\u0645\u0631\u062d\u0644\u0647 \u06f1: \u0646\u0635\u0628 \u0628\u0633\u062a\u0647 HAProxy\">\u0645\u0631\u062d\u0644\u0647 \u06f1: \u0646\u0635\u0628 \u0628\u0633\u062a\u0647 HAProxy<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B2_%D8%AA%D9%86%D8%B8%DB%8C%D9%85%D8%A7%D8%AA_HAProxy\" title=\"\u0645\u0631\u062d\u0644\u0647 \u06f2: \u062a\u0646\u0638\u06cc\u0645\u0627\u062a HAProxy\">\u0645\u0631\u062d\u0644\u0647 \u06f2: \u062a\u0646\u0638\u06cc\u0645\u0627\u062a HAProxy<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B3_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%B3%D8%B1%D9%88%D8%B1_%D8%A8%DA%A9%E2%80%8C%D8%A7%D9%86%D8%AF\" title=\"\u0645\u0631\u062d\u0644\u0647 \u06f3: \u0627\u06cc\u062c\u0627\u062f \u0633\u0631\u0648\u0631 \u0628\u06a9\u200c\u0627\u0646\u062f\">\u0645\u0631\u062d\u0644\u0647 \u06f3: \u0627\u06cc\u062c\u0627\u062f \u0633\u0631\u0648\u0631 \u0628\u06a9\u200c\u0627\u0646\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B4_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D9%81%D8%B1%D8%A7%D9%86%D8%AA%E2%80%8C%D8%A7%D9%86%D8%AF\" title=\"\u0645\u0631\u062d\u0644\u0647 \u06f4: \u0627\u06cc\u062c\u0627\u062f \u0641\u0631\u0627\u0646\u062a\u200c\u0627\u0646\u062f\">\u0645\u0631\u062d\u0644\u0647 \u06f4: \u0627\u06cc\u062c\u0627\u062f \u0641\u0631\u0627\u0646\u062a\u200c\u0627\u0646\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B5_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C_ACL%D9%87%D8%A7_%D9%88_%D8%B4%D8%B1%D8%A7%DB%8C%D8%B7\" title=\"\u0645\u0631\u062d\u0644\u0647 \u06f5: \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc ACL\u0647\u0627 \u0648 \u0634\u0631\u0627\u06cc\u0637\">\u0645\u0631\u062d\u0644\u0647 \u06f5: \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc ACL\u0647\u0627 \u0648 \u0634\u0631\u0627\u06cc\u0637<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B6_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C_%D8%AA%D9%88%D9%82%D9%81_SSL\" title=\"\u0645\u0631\u062d\u0644\u0647 \u06f6: \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u062a\u0648\u0642\u0641 SSL\">\u0645\u0631\u062d\u0644\u0647 \u06f6: \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u062a\u0648\u0642\u0641 SSL<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B7_%D8%A2%D8%B2%D9%85%D8%A7%DB%8C%D8%B4_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C\" title=\"\u0645\u0631\u062d\u0644\u0647 \u06f7: \u0622\u0632\u0645\u0627\u06cc\u0634 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc\">\u0645\u0631\u062d\u0644\u0647 \u06f7: \u0622\u0632\u0645\u0627\u06cc\u0634 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7_HAProxy_%D8%B1%D8%A7_%D8%B1%D9%88%DB%8C_pfSense_%D8%B1%D8%A7%D9%87_%D8%A7%D9%86%D8%AF%D8%A7%D8%B2%DB%8C_%DA%A9%D9%86%DB%8C%D9%85%D8%9F\"><\/span>\u0686\u0631\u0627 HAProxy \u0631\u0627 \u0631\u0648\u06cc pfSense \u0631\u0627\u0647 \u0627\u0646\u062f\u0627\u0632\u06cc \u06a9\u0646\u06cc\u0645\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0631\u0648\u06cc pfSense \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633\u060c \u0628\u0647 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0648 \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0627\u0632 \u06cc\u06a9 \u0631\u0627\u0647\u200c\u062d\u0644 \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0634\u0628\u06a9\u0647\u060c \u0627\u0645\u0646\u06cc\u062a \u0648 \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u0628\u0647 \u062f\u0644\u0627\u06cc\u0644 \u0632\u06cc\u0631 \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u0627\u0633\u062a:<\/p>\n<p><strong>\u06f1. \u06cc\u06a9\u067e\u0627\u0631\u0686\u06af\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u067e\u06cc\u0686\u06cc\u062f\u06af\u06cc \u0632\u06cc\u0631\u0633\u0627\u062e\u062a:<\/strong><\/p>\n<p style=\"text-align: justify;\">pfSense \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u067e\u0644\u062a\u0641\u0631\u0645 \u0686\u0646\u062f\u0645\u0646\u0638\u0648\u0631\u0647\u060c \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0645\u0633\u06cc\u0631\u06cc\u0627\u0628\u06cc\u060c VPN \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0631\u0627 \u062f\u0631 \u06cc\u06a9 \u0633\u06cc\u0633\u062a\u0645 \u0648\u0627\u062d\u062f \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0628\u0627 \u0627\u0641\u0632\u0648\u062f\u0646 HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0628\u0633\u062a\u0647 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u062f\u0631 pfSense\u060c \u0646\u06cc\u0627\u0632\u06cc \u0628\u0647 \u0627\u0633\u062a\u0642\u0631\u0627\u0631 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u062c\u062f\u0627\u06af\u0627\u0646\u0647 \u0628\u0631\u0627\u06cc \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u06cc\u0627 \u0645\u062a\u0639\u0627\u062f\u0644\u200c\u0633\u0627\u0632\u06cc \u0628\u0627\u0631 \u0646\u06cc\u0633\u062a. \u0627\u06cc\u0646 \u06cc\u06a9\u067e\u0627\u0631\u0686\u06af\u06cc \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u062a\u0639\u062f\u0627\u062f \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632\u060c \u0633\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0648 \u06a9\u0627\u0647\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0633\u062e\u062a\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u062f\u0631 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9 \u0648 \u0645\u062a\u0648\u0633\u0637 \u06a9\u0647 \u0645\u0646\u0627\u0628\u0639 \u0645\u062d\u062f\u0648\u062f\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0627\u06cc\u0646 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0628\u0633\u06cc\u0627\u0631 \u0645\u0642\u0631\u0648\u0646\u200c\u0628\u0647\u200c\u0635\u0631\u0641\u0647 \u0627\u0633\u062a.<\/p>\n<p><strong>\u06f2. \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u062a\u0645\u0631\u06a9\u0632:<\/strong><\/p>\n<p style=\"text-align: justify;\">pfSense \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0631\u0627\u0628\u0637 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0648\u0628\u200c\u0645\u062d\u0648\u0631 \u062e\u0648\u062f \u0627\u0645\u06a9\u0627\u0646 \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0645\u0627\u0645 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 HAProxy\u060c \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0628\u062f\u0627\u0646 \u0645\u0639\u0646\u0627\u0633\u062a \u06a9\u0647 \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0642\u0648\u0627\u0646\u06cc\u0646 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0645\u0633\u06cc\u0631\u06cc\u0627\u0628\u06cc \u0648 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u0631\u0627 \u0627\u0632 \u06cc\u06a9 \u06a9\u0646\u0633\u0648\u0644 \u0648\u0627\u062d\u062f \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u062a\u0645\u0631\u06a9\u0632 \u062f\u0631 \u0645\u062f\u06cc\u0631\u06cc\u062a\u060c \u0632\u0645\u0627\u0646 \u0648 \u062a\u0644\u0627\u0634 \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632 \u0628\u0631\u0627\u06cc \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0648 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0634\u0628\u06a9\u0647 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<p><strong>\u06f3. \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u0648\u0628\u200c\u0633\u0631\u0648\u0631\u0647\u0627\u060c \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u06cc \u06cc\u0627 \u067e\u0627\u06cc\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0627\u062f\u0647 \u0631\u0627 \u0645\u06cc\u0632\u0628\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062f\u0633\u062a\u0631\u0633\u06cc \u0627\u0645\u0646 \u0648 \u06a9\u0627\u0631\u0622\u0645\u062f \u062f\u0627\u0631\u0646\u062f. HAProxy \u0631\u0648\u06cc pfSense \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0648\u0631\u0648\u062f\u06cc \u0631\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627 \u0647\u062f\u0627\u06cc\u062a \u06a9\u0646\u062f\u060c \u0628\u0627\u0631 \u0631\u0627 \u0628\u06cc\u0646 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0645\u062a\u0639\u0627\u062f\u0644 \u0633\u0627\u0632\u062f \u0648 \u0627\u0632 \u062f\u0633\u062a\u0631\u0633\u06cc \u0645\u062f\u0627\u0648\u0645 \u0648 \u0628\u0647\u06cc\u0646\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%88%DB%8C%DA%98%DA%AF%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C_HAProxy_%D9%88_%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D8%A2%D9%86%E2%80%8C%D9%87%D8%A7\"><\/span>\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc HAProxy \u0648 \u0627\u0647\u0645\u06cc\u062a \u0622\u0646\u200c\u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">HAProxy \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0628\u0631\u062c\u0633\u062a\u0647\u200c\u0627\u0634 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u0648 \u0645\u062a\u0639\u0627\u062f\u0644\u200c\u0633\u0627\u0632 \u0628\u0627\u0631\u060c \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 pfSense \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647\u060c \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0630\u06a9\u0631\u0634\u062f\u0647 \u062f\u0631 \u0645\u062a\u0646 \u0631\u0627 \u0628\u0627 \u062c\u0632\u0626\u06cc\u0627\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645:<\/p>\n<p><strong>\u06f1. \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0627\u0644\u0627 (\u0628\u0647\u06cc\u0646\u0647\u200c\u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0647\u0632\u0627\u0631\u0627\u0646 \u0627\u062a\u0635\u0627\u0644 \u0647\u0645\u0632\u0645\u0627\u0646):<\/strong><\/p>\n<p style=\"text-align: justify;\">HAProxy \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0639\u0645\u0627\u0631\u06cc \u0633\u0628\u06a9 \u0648 \u0628\u0647\u06cc\u0646\u0647\u200c\u0627\u0634\u060c \u0642\u0627\u062f\u0631 \u0627\u0633\u062a \u062d\u062c\u0645 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0627\u0632 \u062f\u0631\u062e\u0648\u0627\u0633\u062a\u200c\u0647\u0627 \u0648 \u0627\u062a\u0635\u0627\u0644\u0627\u062a \u0647\u0645\u0632\u0645\u0627\u0646 \u0631\u0627 \u0628\u0627 \u062d\u062f\u0627\u0642\u0644 \u0645\u0635\u0631\u0641 \u0645\u0646\u0627\u0628\u0639 \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062a\u0639\u062f\u0627\u062f \u0632\u06cc\u0627\u062f\u06cc \u06a9\u0627\u0631\u0628\u0631 \u06cc\u0627 \u062f\u0633\u062a\u06af\u0627\u0647 \u0628\u0647\u200c\u0637\u0648\u0631 \u0647\u0645\u0632\u0645\u0627\u0646 \u0628\u0647 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0645\u062a\u0635\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f (\u0645\u0627\u0646\u0646\u062f \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u067e\u0631\u062a\u0631\u0627\u0641\u06cc\u06a9 \u06cc\u0627 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u06cc) \u0628\u0633\u06cc\u0627\u0631 \u062d\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a. \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633\u060c HAProxy \u062a\u0623\u062e\u06cc\u0631 \u06a9\u0645\u062a\u0631\u06cc \u062f\u0627\u0631\u062f \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u0634\u0628\u06a9\u0647 \u0631\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647\u06cc \u0628\u0647\u0628\u0648\u062f \u0628\u0628\u062e\u0634\u062f.<\/p>\n<p><strong>\u06f2. \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062f\u0627\u062e\u0644\u06cc \u062f\u0631 pfSense (\u0646\u0635\u0628 \u0648 \u0627\u062f\u063a\u0627\u0645 \u0622\u0633\u0627\u0646):<\/strong><\/p>\n<p style=\"text-align: justify;\">HAProxy \u0628\u0647\u200c\u0635\u0648\u0631\u062a \u06cc\u06a9 \u0628\u0633\u062a\u0647 \u0631\u0633\u0645\u06cc \u062f\u0631 pfSense \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0646\u06cc\u0627\u0632\u06cc \u0628\u0647 \u0646\u0635\u0628 \u062f\u0633\u062a\u06cc \u06cc\u0627 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0646\u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0628\u0633\u062a\u0647 \u0628\u0647\u200c\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0631\u0627\u0628\u0637 \u06a9\u0627\u0631\u0628\u0631\u06cc pfSense \u0627\u062f\u063a\u0627\u0645 \u0634\u062f\u0647 \u0648 \u0627\u0645\u06a9\u0627\u0646 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0633\u0631\u06cc\u0639 \u0648 \u0628\u0635\u0631\u06cc \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u0686\u0646\u062f \u06a9\u0644\u06cc\u06a9\u060c HAProxy \u0631\u0627 \u0646\u0635\u0628 \u06a9\u0631\u062f\u0647 \u0648 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u06cc\u0627 \u0645\u062a\u0639\u0627\u062f\u0644\u200c\u0633\u0627\u0632\u06cc \u0628\u0627\u0631 \u0631\u0627 \u0627\u0639\u0645\u0627\u0644 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0633\u0647\u0648\u0644\u062a \u062f\u0631 \u0646\u0635\u0628 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u060c \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u0628\u0631\u0627\u06cc \u062a\u06cc\u0645\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062a\u062c\u0631\u0628\u0647 \u0645\u062d\u062f\u0648\u062f\u06cc \u062f\u0631 \u0645\u062f\u06cc\u0631\u06cc\u062a \u067e\u0631\u0627\u06a9\u0633\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u0627\u0633\u062a.<\/p>\n<p><strong>\u06f3. TLS (\u0645\u062f\u06cc\u0631\u06cc\u062a \u0633\u0627\u062f\u0647 SSL\/TLS):<\/strong><\/p>\n<p style=\"text-align: justify;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u0631\u0627\u06cc\u062c \u062f\u0631 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u0648\u0628\u060c \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc SSL\/TLS \u0628\u0631\u0627\u06cc \u0627\u0631\u062a\u0628\u0627\u0637\u0627\u062a \u0627\u0645\u0646 \u0627\u0633\u062a. HAProxy \u0627\u0645\u06a9\u0627\u0646 &#8220;\u062a\u0648\u0642\u0641 TLS&#8221; (TLS Termination) \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u0627 \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0631\u0645\u0632\u06af\u0634\u0627\u06cc\u06cc \u062a\u0631\u0627\u0641\u06cc\u06a9 HTTPS \u0631\u0627 \u062f\u0631 \u0644\u0627\u06cc\u0647 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u062f \u0648 \u0633\u067e\u0633 \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0631\u0645\u0632\u06af\u0634\u0627\u06cc\u06cc\u200c\u0634\u062f\u0647 \u0631\u0627 \u0628\u0647 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0647\u062f\u0627\u06cc\u062a \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0686\u0646\u062f\u06cc\u0646 \u0645\u0632\u06cc\u062a \u062f\u0627\u0631\u062f:<\/p>\n<p style=\"text-align: justify;\">&#8211; \u06a9\u0627\u0647\u0634 \u0628\u0627\u0631 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc: \u0628\u0627 \u0627\u0646\u062a\u0642\u0627\u0644 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0631\u0645\u0632\u0646\u06af\u0627\u0631\u06cc \u0648 \u0631\u0645\u0632\u06af\u0634\u0627\u06cc\u06cc \u0628\u0647 HAProxy\u060c \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u0646\u0627\u0628\u0639 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0634 \u062f\u0631\u062e\u0648\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0627\u062e\u062a\u0635\u0627\u0635 \u062f\u0647\u0646\u062f.<br \/>\n&#8211; \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u062a\u0645\u0631\u06a9\u0632 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627: \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc SSL\/TLS \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647\u200c\u0635\u0648\u0631\u062a \u0645\u062a\u0645\u0631\u06a9\u0632 \u062f\u0631 HAProxy \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0631\u062f\u060c \u0628\u0647\u200c\u062c\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0631\u0648\u06cc \u0647\u0631 \u0633\u0631\u0648\u0631 \u062f\u0627\u062e\u0644\u06cc \u062c\u062f\u0627\u06af\u0627\u0646\u0647 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0634\u0648\u0646\u062f.<br \/>\n&#8211; \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u067e\u0631\u0648\u062a\u06a9\u0644\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646: HAProxy \u0627\u0632 \u0646\u0633\u062e\u0647\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f TLS \u0648 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f HTTP\/2 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u0648 \u0627\u0645\u0646\u06cc\u062a \u0627\u0631\u062a\u0628\u0627\u0637\u0627\u062a \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u0628\u062e\u0634\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%AA%D8%AC%D9%85%DB%8C%D8%B9_%D9%81%D8%A7%DB%8C%D8%B1%D9%88%D8%A7%D9%84%D8%8C_%D8%B1%D9%88%D8%AA%D8%B1_%D9%88_%D9%BE%D8%B1%D8%A7%DA%A9%D8%B3%DB%8C_%D9%85%D8%B9%DA%A9%D9%88%D8%B3_%D8%AF%D8%B1_%DB%8C%DA%A9_%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87\"><\/span>\u0645\u0632\u0627\u06cc\u0627\u06cc \u062a\u062c\u0645\u06cc\u0639 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0631\u0648\u062a\u0631 \u0648 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u062f\u0631 \u06cc\u06a9 \u062f\u0633\u062a\u06af\u0627\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0645\u0632\u0627\u06cc\u0627\u06cc \u0632\u06cc\u0631 \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f:<\/p>\n<p style=\"text-align: justify;\">&#8211; \u06a9\u0627\u0647\u0634 \u0646\u0642\u0627\u0637 \u062e\u0631\u0627\u0628\u06cc: \u0628\u0627 \u06a9\u0627\u0647\u0634 \u062a\u0639\u062f\u0627\u062f \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u06cc\u0627 \u0645\u062c\u0627\u0632\u06cc \u062f\u0631 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u060c \u0627\u062d\u062a\u0645\u0627\u0644 \u062e\u0631\u0627\u0628\u06cc\u200c\u0647\u0627\u06cc \u0633\u062e\u062a\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u06cc\u0627 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f.<br \/>\n&#8211; \u0645\u062f\u06cc\u0631\u06cc\u062a \u0633\u0627\u062f\u0647\u200c\u062a\u0631: \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0648 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u062a\u0645\u0627\u0645 \u0627\u062c\u0632\u0627\u06cc \u0634\u0628\u06a9\u0647 \u0627\u0632 \u06cc\u06a9 \u067e\u0644\u062a\u0641\u0631\u0645 \u0648\u0627\u062d\u062f\u060c \u067e\u06cc\u0686\u06cc\u062f\u06af\u06cc\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f.<br \/>\n&#8211; \u0628\u0647\u06cc\u0646\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u0646\u0627\u0628\u0639: \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06cc\u06a9 \u062f\u0633\u062a\u06af\u0627\u0647 \u0628\u0631\u0627\u06cc \u0686\u0646\u062f\u06cc\u0646 \u0639\u0645\u0644\u06a9\u0631\u062f\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0646\u0627\u0628\u0639 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0648 \u0627\u0646\u0631\u0698\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u06a9\u0647 \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u0628\u0631\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u200c\u062a\u0631 \u06cc\u0627 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0628\u0627 \u0645\u0646\u0627\u0628\u0639 \u0645\u062d\u062f\u0648\u062f \u0645\u0641\u06cc\u062f \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF%D9%87%D8%A7%DB%8C_%D8%B9%D9%85%D9%84%DB%8C_HAProxy_%D8%B1%D9%88%DB%8C_pfSense\"><\/span>\u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc HAProxy \u0631\u0648\u06cc pfSense<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0631\u0648\u06cc pfSense \u0628\u0631\u0627\u06cc \u0633\u0646\u0627\u0631\u06cc\u0648\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u060c \u0627\u0632 \u062c\u0645\u0644\u0647:<\/p>\n<p style=\"text-align: justify;\">&#8211; \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0648\u0628: \u0647\u062f\u0627\u06cc\u062a \u062f\u0631\u062e\u0648\u0627\u0633\u062a\u200c\u0647\u0627\u06cc HTTP\/HTTPS \u0628\u0647 \u0686\u0646\u062f\u06cc\u0646 \u0648\u0628\u200c\u0633\u0631\u0648\u0631 \u0628\u0631\u0627\u06cc \u0645\u062a\u0639\u0627\u062f\u0644\u200c\u0633\u0627\u0632\u06cc \u0628\u0627\u0631 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0633\u062a\u0631\u0633\u06cc\u200c\u067e\u0630\u06cc\u0631\u06cc.<br \/>\n&#8211; \u0627\u0645\u0646\u06cc\u062a \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc: \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 HAProxy \u0628\u0631\u0627\u06cc \u0641\u06cc\u0644\u062a\u0631 \u06a9\u0631\u062f\u0646 \u062f\u0631\u062e\u0648\u0627\u0633\u062a\u200c\u0647\u0627 \u0648 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062d\u0645\u0644\u0627\u062a \u0645\u0627\u0646\u0646\u062f DDoS.<br \/>\n&#8211; \u062f\u0633\u062a\u0631\u0633\u06cc \u0627\u0632 \u0631\u0627\u0647 \u062f\u0648\u0631: \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0646 \u062f\u0633\u062a\u0631\u0633\u06cc \u0627\u0645\u0646 \u0628\u0647 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633\u060c \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0628 \u0628\u0627 VPN.<br \/>\n&#8211; \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0645\u06cc\u06a9\u0631\u0648\u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627: \u0647\u062f\u0627\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0628\u0647 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062f\u0631 \u0645\u0639\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0645\u06cc\u06a9\u0631\u0648\u0633\u0631\u0648\u06cc\u0633.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%A7%D8%AD%D9%84_%D9%86%D8%B5%D8%A8_%D9%88_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C_HAProxy_%D8%AF%D8%B1_%D9%81%D8%A7%DB%8C%D8%B1%D9%88%D8%A7%D9%84_pfSense\"><\/span>\u0645\u0631\u0627\u062d\u0644 \u0646\u0635\u0628 \u0648 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc HAProxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u067e\u0631\u0627\u06a9\u0633\u06cc \u0645\u0639\u06a9\u0648\u0633 \u062f\u0631 pfSense \u0641\u0631\u0622\u06cc\u0646\u062f\u06cc \u06af\u0627\u0645\u200c\u0628\u0647\u200c\u06af\u0627\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u0647\u062f\u0627\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0628\u0647 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0631\u0627 \u0628\u0627 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0648 \u0627\u0645\u0646\u06cc\u062a \u0628\u0627\u0644\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647\u060c \u0645\u0631\u0627\u062d\u0644 \u0646\u0635\u0628 \u0648 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc HAProxy \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062a\u0648\u0636\u06cc\u062d\u0627\u062a \u062f\u0642\u06cc\u0642 \u0647\u0631 \u0645\u0631\u062d\u0644\u0647 \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0631\u0627\u0647\u0646\u0645\u0627 \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 HAProxy \u0631\u0627 \u0628\u0647\u200c\u062f\u0631\u0633\u062a\u06cc \u0646\u0635\u0628 \u0648 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B1_%D9%86%D8%B5%D8%A8_%D8%A8%D8%B3%D8%AA%D9%87_HAProxy\"><\/span>\u0645\u0631\u062d\u0644\u0647 \u06f1: \u0646\u0635\u0628 \u0628\u0633\u062a\u0647 HAProxy<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0631\u0627\u06cc \u0634\u0631\u0648\u0639\u060c \u0628\u0633\u062a\u0647 HAProxy \u0628\u0627\u06cc\u062f \u0631\u0648\u06cc pfSense \u0646\u0635\u0628 \u0634\u0648\u062f. \u0645\u0631\u0627\u062d\u0644 \u0632\u06cc\u0631 \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f:<\/p>\n<ol style=\"text-align: justify;\">\n<li>\u0648\u0631\u0648\u062f \u0628\u0647 \u0631\u0627\u0628\u0637 \u0648\u0628 pfSense: \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0631\u0648\u0631\u06af\u0631\u060c \u0628\u0647 \u0631\u0627\u0628\u0637 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0648\u0628 pfSense \u0648\u0627\u0631\u062f \u0634\u0648\u06cc\u062f (\u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u062f\u0631\u0633 IP \u062f\u0633\u062a\u06af\u0627\u0647 pfSense \u0642\u0627\u0628\u0644 \u062f\u0633\u062a\u0631\u0633\u06cc \u0627\u0633\u062a).<\/li>\n<li>\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u0633\u062a\u0647\u200c\u0647\u0627: \u0628\u0647 \u0645\u0646\u0648\u06cc System \u0628\u0631\u0648\u06cc\u062f\u060c \u0633\u067e\u0633 Package Manager \u0648 \u0628\u0639\u062f Available Packages \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u062c\u0633\u062a\u062c\u0648\u06cc HAProxy: \u062f\u0631 \u06a9\u0627\u062f\u0631 \u062c\u0633\u062a\u062c\u0648\u060c \u0639\u0628\u0627\u0631\u062a &#8220;HAProxy&#8221; \u0631\u0627 \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u0633\u062a\u0647 \u0645\u0631\u0628\u0648\u0637\u0647 \u0646\u0645\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0634\u0648\u062f.<\/li>\n<li>\u0646\u0635\u0628 \u0628\u0633\u062a\u0647: \u0631\u0648\u06cc \u062f\u06a9\u0645\u0647 Install \u06a9\u0646\u0627\u0631 \u0628\u0633\u062a\u0647 HAProxy \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f \u0648 \u0646\u0635\u0628 \u0631\u0627 \u062a\u0623\u06cc\u06cc\u062f \u06a9\u0646\u06cc\u062f. \u0641\u0631\u0622\u06cc\u0646\u062f \u0646\u0635\u0628 \u0686\u0646\u062f \u062f\u0642\u06cc\u0642\u0647 \u0637\u0648\u0644 \u0645\u06cc\u200c\u06a9\u0634\u062f \u0648 \u067e\u0633 \u0627\u0632 \u0627\u062a\u0645\u0627\u0645\u060c HAProxy \u062f\u0631 \u0645\u0646\u0648\u06cc Services \u0642\u0627\u0628\u0644 \u062f\u0633\u062a\u0631\u0633\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u062a\u0648\u0636\u06cc\u062d: \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0628\u0633\u062a\u0647 \u0631\u0633\u0645\u06cc \u062f\u0631 pfSense \u0646\u0635\u0628 \u0634\u062f\u0647 \u0648 \u0622\u0645\u0627\u062f\u0647 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0627\u0633\u062a. \u0646\u0635\u0628 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0631\u0627\u0628\u0637 \u0648\u0628\u060c \u0641\u0631\u0622\u06cc\u0646\u062f \u0631\u0627 \u0633\u0627\u062f\u0647 \u0648 \u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062f\u0633\u062a\u0648\u0631\u0627\u062a \u062e\u0637 \u0641\u0631\u0645\u0627\u0646 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B2_%D8%AA%D9%86%D8%B8%DB%8C%D9%85%D8%A7%D8%AA_HAProxy\"><\/span>\u0645\u0631\u062d\u0644\u0647 \u06f2: \u062a\u0646\u0638\u06cc\u0645\u0627\u062a HAProxy<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u067e\u0633 \u0627\u0632 \u0646\u0635\u0628\u060c \u0628\u0627\u06cc\u062f \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0627\u0648\u0644\u06cc\u0647 HAProxy \u0631\u0627 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u06a9\u0646\u06cc\u062f:<\/p>\n<ol style=\"text-align: justify;\">\n<li>\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a HAProxy: \u0628\u0647 \u0645\u0646\u0648\u06cc Services \u0628\u0631\u0648\u06cc\u062f \u0648 HAProxy \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0641\u0639\u0627\u0644\u200c\u0633\u0627\u0632\u06cc HAProxy: \u062f\u0631 \u062a\u0628 Settings\u060c \u06af\u0632\u06cc\u0646\u0647 Enable HAProxy \u0631\u0627 \u0639\u0644\u0627\u0645\u062a \u0628\u0632\u0646\u06cc\u062f \u062a\u0627 \u0633\u0631\u0648\u06cc\u0633 \u0641\u0639\u0627\u0644 \u0634\u0648\u062f.<\/li>\n<li>\u062d\u062f\u0627\u06a9\u062b\u0631 \u0627\u062a\u0635\u0627\u0644\u0627\u062a (Max Connections): \u0627\u06cc\u0646 \u0645\u0642\u062f\u0627\u0631 \u0631\u0627 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f. \u0628\u0631\u0627\u06cc \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u060c \u0639\u062f\u062f \u06f2\u06f0\u06f0\u06f0 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062a\u0646\u0638\u06cc\u0645 \u062a\u0639\u062f\u0627\u062f \u0627\u062a\u0635\u0627\u0644\u0627\u062a \u0647\u0645\u0632\u0645\u0627\u0646 \u0631\u0627 \u0645\u062d\u062f\u0648\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li>\u067e\u0648\u0631\u062a \u0622\u0645\u0627\u0631 \u062f\u0627\u062e\u0644\u06cc (Internal Stats Port): \u067e\u0648\u0631\u062a \u06f2\u06f2\u06f0\u06f0 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0641\u0639\u0627\u0644\u200c\u0633\u0627\u0632\u06cc \u0635\u0641\u062d\u0647 \u0622\u0645\u0627\u0631 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0635\u0641\u062d\u0647 \u0628\u0631\u0627\u06cc \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0639\u0645\u0644\u06a9\u0631\u062f HAProxy \u0645\u0641\u06cc\u062f \u0627\u0633\u062a.<\/li>\n<li>\u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0644\u0627\u06af:\n<ul>\n<li>\u0647\u0627\u0633\u062a Syslog \u0631\u06cc\u0645\u0648\u062a: \u0622\u062f\u0631\u0633 <code>\/var\/run\/log<\/code> \u0631\u0627 \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0633\u0637\u062d Syslog: \u06af\u0632\u06cc\u0646\u0647 local0 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0633\u0637\u062d \u0644\u0627\u06af: \u0628\u0633\u062a\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632\u060c Debugging (\u0628\u0631\u0627\u06cc \u0639\u06cc\u0628\u200c\u06cc\u0627\u0628\u06cc \u062f\u0642\u06cc\u0642) \u06cc\u0627 Informational (\u0628\u0631\u0627\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u06a9\u0644\u06cc) \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<\/li>\n<li>\u0633\u0631\u0648\u0631\u0647\u0627\u06cc DNS: \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 HAProxy \u0628\u0631\u0627\u06cc \u0631\u0641\u0639 \u0646\u0627\u0645\u200c\u0647\u0627\u06cc \u062f\u0627\u0645\u0646\u0647 \u062e\u0635\u0648\u0635\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0633\u0631\u0648\u0631 DNS \u062f\u0627\u062e\u0644\u06cc \u0631\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627\u060c \u0622\u062f\u0631\u0633 <code>\u06f1\u06f2\u06f7.\u06f0.\u06f0.\u06f1<\/code> (localhost \u062f\u0633\u062a\u06af\u0627\u0647 pfSense) \u0631\u0627 \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0630\u062e\u06cc\u0631\u0647 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a: \u0631\u0648\u06cc Save \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0627\u0639\u0645\u0627\u0644 \u0634\u0648\u0646\u062f.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u062a\u0648\u0636\u06cc\u062d: \u0627\u06cc\u0646 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u067e\u0627\u06cc\u0647\u200c\u0627\u06cc\u060c HAProxy \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0641\u0639\u0627\u0644\u200c\u0633\u0627\u0632\u06cc \u067e\u0648\u0631\u062a \u0622\u0645\u0627\u0631 \u0627\u0645\u06a9\u0627\u0646 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0639\u0645\u0644\u06a9\u0631\u062f \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0644\u0627\u06af \u0628\u0647 \u0639\u06cc\u0628\u200c\u06cc\u0627\u0628\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 DNS \u062f\u0627\u062e\u0644\u06cc \u0628\u0631\u0627\u06cc \u0631\u0641\u0639 \u0646\u0627\u0645\u200c\u0647\u0627\u06cc \u062f\u0627\u0645\u0646\u0647 \u062e\u0635\u0648\u0635\u06cc \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B3_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%B3%D8%B1%D9%88%D8%B1_%D8%A8%DA%A9%E2%80%8C%D8%A7%D9%86%D8%AF\"><\/span>\u0645\u0631\u062d\u0644\u0647 \u06f3: \u0627\u06cc\u062c\u0627\u062f \u0633\u0631\u0648\u0631 \u0628\u06a9\u200c\u0627\u0646\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u06a9\u200c\u0627\u0646\u062f\u200c\u0647\u0627 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 HAProxy \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0631\u0627 \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u0647\u062f\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0628\u06a9\u200c\u0627\u0646\u062f:<\/p>\n<ol style=\"text-align: justify;\">\n<li>\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0628 \u0628\u06a9\u200c\u0627\u0646\u062f: \u062f\u0631 \u0645\u0646\u0648\u06cc HAProxy\u060c \u0628\u0647 \u062a\u0628 Backend \u0628\u0631\u0648\u06cc\u062f \u0648 \u0631\u0648\u06cc Add \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0628\u06a9\u200c\u0627\u0646\u062f:\n<ul>\n<li>\u0646\u0627\u0645: \u06cc\u06a9 \u0634\u0646\u0627\u0633\u0647 \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f (\u0645\u062b\u0644\u0627\u064b <code>web_server_1<\/code>).<\/li>\n<li>\u0644\u06cc\u0633\u062a \u0633\u0631\u0648\u0631\u0647\u0627:\n<ul>\n<li>\u0646\u0627\u0645: \u0646\u0627\u0645\u06cc \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u0631 \u0628\u06a9\u200c\u0627\u0646\u062f \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f. \u0627\u06af\u0631 \u0686\u0646\u062f\u06cc\u0646 \u0628\u06a9\u200c\u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u06cc\u06a9 \u0633\u0631\u0648\u06cc\u0633 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u060c \u0646\u0627\u0645\u200c\u0647\u0627 \u0628\u0627\u06cc\u062f \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u0628\u0627\u0634\u0646\u062f.<\/li>\n<li>Forwardto: \u06af\u0632\u06cc\u0646\u0647 Address+Port \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0622\u062f\u0631\u0633: \u0622\u062f\u0631\u0633 IP \u06cc\u0627 FQDN \u0633\u0631\u0648\u06cc\u0633 \u062f\u0627\u062e\u0644\u06cc \u0631\u0627 \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f (\u0645\u062b\u0644\u0627\u064b \u0622\u062f\u0631\u0633 \u0648\u0628\u200c\u0633\u0631\u0648\u0631).<\/li>\n<li>\u0631\u0645\u0632\u0646\u06af\u0627\u0631\u06cc (SSL): \u0627\u06af\u0631 \u0633\u0631\u0648\u06cc\u0633 \u0627\u0632 HTTPS \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0627\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u0641\u0639\u0627\u0644 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0628\u0631\u0631\u0633\u06cc SSL: \u0627\u06af\u0631 \u0627\u0632 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 \u062e\u0648\u062f\u0627\u0645\u0636\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u0631\u0648\u06cc No \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<\/li>\n<li>\u0628\u0631\u0631\u0633\u06cc \u0633\u0644\u0627\u0645\u062a (Health Checking): \u0627\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u0641\u0639\u0627\u0644 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0648\u0636\u0639\u06cc\u062a \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u0628\u06a9\u200c\u0627\u0646\u062f \u0628\u0631\u0631\u0633\u06cc \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc HTTPS\u060c \u06af\u0632\u06cc\u0646\u0647 Basic \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u061b \u0628\u0631\u0627\u06cc HTTP\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f Basic \u06cc\u0627 HTTP \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f. \u0648\u0636\u0639\u06cc\u062a \u0633\u0644\u0627\u0645\u062a \u062f\u0631 \u0635\u0641\u062d\u0647 \u0622\u0645\u0627\u0631 \u0646\u0645\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/li>\n<\/ul>\n<\/li>\n<li>\u0630\u062e\u06cc\u0631\u0647 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a: \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0631\u0627 \u0630\u062e\u06cc\u0631\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u0647\u0634\u062f\u0627\u0631 \u0645\u0647\u0645: \u0627\u0632 \u06a9\u067e\u06cc \u06a9\u0631\u062f\u0646 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a Backend \u0645\u0648\u062c\u0648\u062f \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f. \u0647\u0645\u06cc\u0634\u0647 \u0628\u06a9\u200c\u0627\u0646\u062f \u062c\u062f\u06cc\u062f \u0631\u0627 \u0627\u0632 \u0627\u0628\u062a\u062f\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f\u060c \u0632\u06cc\u0631\u0627 \u06a9\u067e\u06cc\u200c\u0628\u0631\u062f\u0627\u0631\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0634\u0646\u0627\u0633\u0647\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u0634\u0648\u062f \u06a9\u0647 \u0645\u0646\u062c\u0631 \u0628\u0647 \u062e\u0637\u0627\u06cc &#8220;Too Many Redirects&#8221; \u062f\u0631 \u0645\u0631\u0648\u0631\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p style=\"text-align: justify;\">\u062a\u0648\u0636\u06cc\u062d: \u0628\u06a9\u200c\u0627\u0646\u062f \u0645\u0634\u062e\u0635 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0628\u0647 \u06a9\u062f\u0627\u0645 \u0633\u0631\u0648\u0631 \u062f\u0627\u062e\u0644\u06cc \u0647\u062f\u0627\u06cc\u062a \u0634\u0648\u062f. \u0628\u0631\u0631\u0633\u06cc \u0633\u0644\u0627\u0645\u062a \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 HAProxy \u0641\u0642\u0637 \u0628\u0647 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u0641\u0639\u0627\u0644 \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0627\u0631\u0633\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0648 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a SSL \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u0627\u0645\u0646 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B4_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D9%81%D8%B1%D8%A7%D9%86%D8%AA%E2%80%8C%D8%A7%D9%86%D8%AF\"><\/span>\u0645\u0631\u062d\u0644\u0647 \u06f4: \u0627\u06cc\u062c\u0627\u062f \u0641\u0631\u0627\u0646\u062a\u200c\u0627\u0646\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0641\u0631\u0627\u0646\u062a\u200c\u0627\u0646\u062f \u0646\u0642\u0637\u0647 \u0648\u0631\u0648\u062f\u06cc \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0628\u0647 HAProxy \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc:<\/p>\n<ol style=\"text-align: justify;\">\n<li>\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0628 \u0641\u0631\u0627\u0646\u062a\u200c\u0627\u0646\u062f: \u062f\u0631 \u0645\u0646\u0648\u06cc HAProxy\u060c \u0628\u0647 \u062a\u0628 Frontend \u0628\u0631\u0648\u06cc\u062f \u0648 \u0631\u0648\u06cc Add \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0641\u0631\u0627\u0646\u062a\u200c\u0627\u0646\u062f:\n<ul>\n<li>\u0646\u0627\u0645: \u06cc\u06a9 \u0646\u0627\u0645 \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f (\u0645\u062b\u0644\u0627\u064b <code>frontend_main<\/code>).<\/li>\n<li>\u0648\u0636\u0639\u06cc\u062a: \u06af\u0632\u06cc\u0646\u0647 Active \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0622\u062f\u0631\u0633 \u062e\u0627\u0631\u062c\u06cc:\n<ul>\n<li>\u0622\u062f\u0631\u0633 \u06af\u0648\u0634 \u062f\u0627\u062f\u0646 (Listen Address): \u0628\u0633\u062a\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632\u060c \u0622\u062f\u0631\u0633 IP WAN \u06cc\u0627 LAN \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u067e\u0648\u0631\u062a: \u067e\u0648\u0631\u062a \u0645\u0648\u0631\u062f\u0646\u0638\u0631 \u0631\u0627 \u0645\u0634\u062e\u0635 \u06a9\u0646\u06cc\u062f (\u0645\u062b\u0644\u0627\u064b \u06f4\u06f4\u06f3 \u0628\u0631\u0627\u06cc HTTPS).<\/li>\n<\/ul>\n<\/li>\n<li>\u062a\u0648\u0642\u0641 SSL (SSL Offloading): \u0627\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u0641\u0639\u0627\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 Let\u2019s Encrypt \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0646\u0648\u0639: \u06af\u0632\u06cc\u0646\u0647 http\/https(offloading) \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<\/li>\n<li>\u0630\u062e\u06cc\u0631\u0647 \u0648 \u0627\u0639\u0645\u0627\u0644: \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0631\u0627 \u0630\u062e\u06cc\u0631\u0647 \u0648 \u0627\u0639\u0645\u0627\u0644 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u062a\u0648\u0636\u06cc\u062d: \u0641\u0631\u0627\u0646\u062a\u200c\u0627\u0646\u062f \u0645\u0634\u062e\u0635 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 HAProxy \u0631\u0648\u06cc \u06a9\u062f\u0627\u0645 \u0622\u062f\u0631\u0633 \u0648 \u067e\u0648\u0631\u062a \u0628\u0647 \u062a\u0631\u0627\u0641\u06cc\u06a9 \u06af\u0648\u0634 \u062f\u0647\u062f. \u0641\u0639\u0627\u0644\u200c\u0633\u0627\u0632\u06cc SSL Offloading \u0628\u0647 HAProxy \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u0631\u0645\u0632\u06af\u0634\u0627\u06cc\u06cc HTTPS \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u062f \u0648 \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0631\u0627 \u0628\u0647 \u0628\u06a9\u200c\u0627\u0646\u062f \u0647\u062f\u0627\u06cc\u062a \u06a9\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B5_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C_ACL%D9%87%D8%A7_%D9%88_%D8%B4%D8%B1%D8%A7%DB%8C%D8%B7\"><\/span>\u0645\u0631\u062d\u0644\u0647 \u06f5: \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc ACL\u0647\u0627 \u0648 \u0634\u0631\u0627\u06cc\u0637<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0627\u06af\u0631 \u0686\u0646\u062f\u06cc\u0646 \u0633\u0631\u0648\u06cc\u0633 \u062f\u0627\u0631\u06cc\u062f \u0648 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0647\u062f\u0627\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0628\u0631 \u0627\u0633\u0627\u0633 \u062f\u0627\u0645\u0646\u0647 \u06cc\u0627 URL \u062f\u0627\u0631\u06cc\u062f\u060c ACL\u0647\u0627 (\u0644\u06cc\u0633\u062a\u200c\u0647\u0627\u06cc \u06a9\u0646\u062a\u0631\u0644 \u062f\u0633\u062a\u0631\u0633\u06cc) \u0631\u0627 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f:<\/p>\n<ol style=\"text-align: justify;\">\n<li>\u0627\u0641\u0632\u0648\u062f\u0646 ACL:\n<ul>\n<li>\u0646\u0627\u0645: \u0646\u0627\u0645\u06cc \u0628\u0631\u0627\u06cc ACL \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0627 \u0634\u0631\u0637 \u062f\u0631 \u0627\u06a9\u0634\u0646 \u0645\u0637\u0627\u0628\u0642\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/li>\n<li>\u0639\u0628\u0627\u0631\u062a (Expression): \u0639\u0628\u0627\u0631\u062a\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f (\u0645\u062b\u0644\u0627\u064b &#8220;Host starts with&#8221;).<\/li>\n<li>\u0645\u0642\u062f\u0627\u0631: \u0645\u0642\u062f\u0627\u0631\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0645\u0637\u0627\u0628\u0642\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0631\u0627 \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f (\u0628\u0633\u062a\u0647 \u0628\u0647 \u0639\u0628\u0627\u0631\u062a \u0627\u0646\u062a\u062e\u0627\u0628\u200c\u0634\u062f\u0647).<\/li>\n<\/ul>\n<\/li>\n<li>\u0627\u0641\u0632\u0648\u062f\u0646 \u0627\u06a9\u0634\u0646\u200c\u0647\u0627:\n<ul>\n<li>\u0627\u06a9\u0634\u0646: \u06af\u0632\u06cc\u0646\u0647 Use Backend \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0628\u06a9\u200c\u0627\u0646\u062f: \u0628\u06a9\u200c\u0627\u0646\u062f \u0645\u0648\u0631\u062f\u0646\u0638\u0631 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0646\u0627\u0645\u200c\u0647\u0627\u06cc ACL \u0634\u0631\u0637: \u0646\u0627\u0645 ACL \u0627\u06cc\u062c\u0627\u062f\u0634\u062f\u0647 \u0631\u0627 \u0648\u0627\u0631\u062f \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0628\u06a9\u200c\u0627\u0646\u062f \u067e\u06cc\u0634\u200c\u0641\u0631\u0636: \u0628\u06a9\u200c\u0627\u0646\u062f\u06cc \u0631\u0627 \u0645\u0634\u062e\u0635 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0639\u062f\u0645 \u062a\u0637\u0627\u0628\u0642 \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 ACL \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f.<\/li>\n<\/ul>\n<\/li>\n<li>\u0630\u062e\u06cc\u0631\u0647 \u0648 \u0627\u0639\u0645\u0627\u0644: \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0631\u0627 \u0630\u062e\u06cc\u0631\u0647 \u0648 \u0627\u0639\u0645\u0627\u0644 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u062a\u0648\u0636\u06cc\u062d: ACL\u0647\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0631\u0627 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0646\u0627\u0645 \u062f\u0627\u0645\u0646\u0647 \u06cc\u0627 \u0645\u0633\u06cc\u0631 URL \u0628\u0647 \u0628\u06a9\u200c\u0627\u0646\u062f\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0647\u062f\u0627\u06cc\u062a \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a \u0628\u0631\u0627\u06cc \u0645\u06cc\u0632\u0628\u0627\u0646\u06cc \u0686\u0646\u062f\u06cc\u0646 \u0633\u0631\u0648\u06cc\u0633 \u0631\u0648\u06cc \u06cc\u06a9 \u0622\u062f\u0631\u0633 IP \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B6_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C_%D8%AA%D9%88%D9%82%D9%81_SSL\"><\/span>\u0645\u0631\u062d\u0644\u0647 \u06f6: \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u062a\u0648\u0642\u0641 SSL<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0631\u0627\u06cc \u0647\u0631 \u062f\u0627\u0645\u0646\u0647\u200c\u0627\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0631\u062d\u0644\u0647 \u0642\u0628\u0644 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0634\u062f\u0647\u060c \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 SSL \u0631\u0627 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f:<\/p>\n<ol style=\"text-align: justify;\">\n<li>\u0627\u0646\u062a\u062e\u0627\u0628 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647: \u06cc\u06a9 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0641\u0639\u0627\u0644\u200c\u0633\u0627\u0632\u06cc ACL \u0628\u0631\u0627\u06cc \u0646\u0627\u0645\u200c\u0647\u0627\u06cc \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647:\n<ul>\n<li>\u06af\u0632\u06cc\u0646\u0647 Add ACL for certificate CommonName \u0631\u0627 \u0639\u0644\u0627\u0645\u062a \u0628\u0632\u0646\u06cc\u062f.<\/li>\n<li>\u06af\u0632\u06cc\u0646\u0647 Add ACL for certificate Subject Alternative Names \u0631\u0627 \u0639\u0644\u0627\u0645\u062a \u0628\u0632\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<\/li>\n<li>\u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u0627\u0636\u0627\u0641\u06cc: \u0627\u06af\u0631 \u0686\u0646\u062f\u06cc\u0646 \u062f\u0627\u0645\u0646\u0647 \u0628\u0627 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062f\u0627\u0631\u06cc\u062f\u060c \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0628\u062e\u0634 Additional certificates \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0630\u062e\u06cc\u0631\u0647 \u0648 \u0627\u0639\u0645\u0627\u0644: \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0631\u0627 \u0630\u062e\u06cc\u0631\u0647 \u0648 \u0627\u0639\u0645\u0627\u0644 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u062a\u0648\u0636\u06cc\u062d: \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc SSL \u0628\u0647\u200c\u062f\u0631\u0633\u062a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0627\u0645\u0646\u0647\u200c\u0647\u0627 \u0627\u0639\u0645\u0627\u0644 \u0634\u0648\u0646\u062f\u060c \u0648 ACL\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0628\u0647\u200c\u0637\u0648\u0631 \u062e\u0648\u062f\u06a9\u0627\u0631 \u0628\u0631\u0627\u06cc \u0647\u062f\u0627\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%AD%D9%84%D9%87_%DB%B7_%D8%A2%D8%B2%D9%85%D8%A7%DB%8C%D8%B4_%D9%BE%DB%8C%DA%A9%D8%B1%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u0645\u0631\u062d\u0644\u0647 \u06f7: \u0622\u0632\u0645\u0627\u06cc\u0634 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0631\u0627\u06cc \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u0639\u0645\u0644\u06a9\u0631\u062f \u0635\u062d\u06cc\u062d\u060c \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0631\u0627 \u0622\u0632\u0645\u0627\u06cc\u0634 \u06a9\u0646\u06cc\u062f:<\/p>\n<ol style=\"text-align: justify;\">\n<li>\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062f\u0627\u0645\u0646\u0647 \u062e\u0635\u0648\u0635\u06cc: \u062f\u0631 \u0645\u0631\u0648\u0631\u06af\u0631\u060c \u0628\u0647 \u062f\u0627\u0645\u0646\u0647 \u062e\u0635\u0648\u0635\u06cc \u062e\u0648\u062f \u0628\u0631\u0648\u06cc\u062f (\u0645\u062b\u0644\u0627\u064b <code>https:\/\/web.example.com<\/code>).<\/li>\n<li>\u0628\u0631\u0631\u0633\u06cc \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631:\n<ul>\n<li>\u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 SSL \u0628\u0647\u200c\u062f\u0631\u0633\u062a\u06cc \u0627\u0639\u0645\u0627\u0644 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f.<\/li>\n<li>\u062a\u0631\u0627\u0641\u06cc\u06a9 \u0628\u0647 \u0633\u0631\u0648\u06cc\u0633 \u0628\u06a9\u200c\u0627\u0646\u062f \u0645\u0646\u0627\u0633\u0628 \u0647\u062f\u0627\u06cc\u062a \u0634\u0648\u062f.<\/li>\n<li>\u0635\u0641\u062d\u0647 \u0622\u0645\u0627\u0631 \u0631\u0648\u06cc \u067e\u0648\u0631\u062a \u062f\u0627\u062e\u0644\u06cc (\u0645\u062b\u0644\u0627\u064b \u06f2\u06f2\u06f0\u06f0) \u0642\u0627\u0628\u0644 \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0627\u0634\u062f.<\/li>\n<\/ul>\n<\/li>\n<li>\u0628\u0631\u0631\u0633\u06cc \u0644\u0627\u06af\u200c\u0647\u0627: \u0628\u0631\u0627\u06cc \u0639\u06cc\u0628\u200c\u06cc\u0627\u0628\u06cc\u060c \u0628\u0647 \u0645\u0646\u0648\u06cc Status &gt; System Logs &gt; HAProxy \u0628\u0631\u0648\u06cc\u062f \u0648 \u0644\u0627\u06af\u200c\u0647\u0627 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u062a\u0648\u0636\u06cc\u062d: \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u062a\u0623\u06cc\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 HAProxy \u0628\u0647\u200c\u062f\u0631\u0633\u062a\u06cc \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0628\u0647\u200c\u0635\u0648\u0631\u062a \u0627\u0645\u0646 \u0648 \u062f\u0642\u06cc\u0642 \u0647\u062f\u0627\u06cc\u062a \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0631\u0631\u0633\u06cc \u0644\u0627\u06af\u200c\u0647\u0627 \u0628\u0647 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0645\u0634\u06a9\u0644\u0627\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>\u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u06cc\u06a9\u06cc \u0627\u0632 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631\u06cc\u0646 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u200c\u0628\u0627\u0632 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0634\u0628\u06a9\u0647 \u0648 \u0627\u0645\u0646\u06cc\u062a \u062f\u0631 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0648 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u067e\u0644\u062a\u0641\u0631\u0645 \u06a9\u0647 \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0633\u06cc\u0633\u062a\u0645\u200c\u0639\u0627\u0645\u0644 FreeBSD \u062a\u0648\u0633\u0639\u0647 \u06cc\u0627\u0641\u062a\u0647\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u0634 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0645\u0633\u06cc\u0631\u06cc\u0627\u0628\u06cc\u060c VPN \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0634\u0628\u06a9\u0647\u060c \u0628\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u062d\u0628\u0648\u0628 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. pfSense \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0639\u0645\u0627\u0644 \u0642\u0648\u0627\u0646\u06cc\u0646 &hellip;<\/p>\n","protected":false},"author":1417,"featured_media":6629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130,324,228],"tags":[],"class_list":["post-6628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-training","category-devops","category-others"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.0 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\" \/>\n<meta property=\"og:description\" content=\"\u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u06cc\u06a9\u06cc \u0627\u0632 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631\u06cc\u0646 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u200c\u0628\u0627\u0632 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0634\u0628\u06a9\u0647 \u0648 \u0627\u0645\u0646\u06cc\u062a \u062f\u0631 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0648 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u067e\u0644\u062a\u0641\u0631\u0645 \u06a9\u0647 \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0633\u06cc\u0633\u062a\u0645\u200c\u0639\u0627\u0645\u0644 FreeBSD \u062a\u0648\u0633\u0639\u0647 \u06cc\u0627\u0641\u062a\u0647\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u0634 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0645\u0633\u06cc\u0631\u06cc\u0627\u0628\u06cc\u060c VPN \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0634\u0628\u06a9\u0647\u060c \u0628\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u062d\u0628\u0648\u0628 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. pfSense \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0639\u0645\u0627\u0644 \u0642\u0648\u0627\u0646\u06cc\u0646 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-22T04:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"\u0627\u062f\u0645\u06cc\u0646\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acto_bit\" \/>\n<meta name=\"twitter:site\" content=\"@acto_bit\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0627\u062f\u0645\u06cc\u0646\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/\"},\"author\":{\"name\":\"\u0627\u062f\u0645\u06cc\u0646\",\"@id\":\"https:\/\/actobit.com\/actomag\/#\/schema\/person\/373a1606772afbdbc09b93f7b2e5a95e\"},\"headline\":\"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\",\"datePublished\":\"2025-04-22T04:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/\"},\"wordCount\":228,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/actobit.com\/actomag\/#organization\"},\"image\":{\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp\",\"articleSection\":[\"\u062f\u0627\u0646\u0634\u0646\u0627\u0645\u0647\",\"\u062f\u0648\u0627\u067e\u0633\",\"\u0633\u0627\u06cc\u0631\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/\",\"url\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/\",\"name\":\"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\",\"isPartOf\":{\"@id\":\"https:\/\/actobit.com\/actomag\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp\",\"datePublished\":\"2025-04-22T04:21:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage\",\"url\":\"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp\",\"contentUrl\":\"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp\",\"width\":1200,\"height\":800,\"caption\":\"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\/\/actobit.com\/actomag\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/actobit.com\/actomag\/#website\",\"url\":\"https:\/\/actobit.com\/actomag\/\",\"name\":\"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a\",\"description\":\"\u0628\u0644\u0627\u06af \u062c\u0627\u0645\u0639 \u0627\u06a9\u062a\u0648\u0628\u06cc\u062a\",\"publisher\":{\"@id\":\"https:\/\/actobit.com\/actomag\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/actobit.com\/actomag\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/actobit.com\/actomag\/#organization\",\"name\":\"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a\",\"url\":\"https:\/\/actobit.com\/actomag\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/actobit.com\/actomag\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2020\/06\/actomag.png\",\"contentUrl\":\"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2020\/06\/actomag.png\",\"width\":599,\"height\":98,\"caption\":\"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a\"},\"image\":{\"@id\":\"https:\/\/actobit.com\/actomag\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/acto_bit\",\"https:\/\/www.instagram.com\/actobit\/\",\"https:\/\/www.linkedin.com\/in\/actobit\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/actobit.com\/actomag\/#\/schema\/person\/373a1606772afbdbc09b93f7b2e5a95e\",\"name\":\"\u0627\u062f\u0645\u06cc\u0646\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/actobit.com\/actomag\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e4c0c194c66063a6885612821c9056cb334a69e1c297cb9de1e0ae7c23ba45fd?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e4c0c194c66063a6885612821c9056cb334a69e1c297cb9de1e0ae7c23ba45fd?s=96&d=wavatar&r=g\",\"caption\":\"\u0627\u062f\u0645\u06cc\u0646\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc","og_description":"\u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u06cc\u06a9\u06cc \u0627\u0632 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631\u06cc\u0646 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u200c\u0628\u0627\u0632 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0634\u0628\u06a9\u0647 \u0648 \u0627\u0645\u0646\u06cc\u062a \u062f\u0631 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0648 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u067e\u0644\u062a\u0641\u0631\u0645 \u06a9\u0647 \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0633\u06cc\u0633\u062a\u0645\u200c\u0639\u0627\u0645\u0644 FreeBSD \u062a\u0648\u0633\u0639\u0647 \u06cc\u0627\u0641\u062a\u0647\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u0634 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644\u060c \u0645\u0633\u06cc\u0631\u06cc\u0627\u0628\u06cc\u060c VPN \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0634\u0628\u06a9\u0647\u060c \u0628\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u062d\u0628\u0648\u0628 \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u0627\u0646 \u0634\u0628\u06a9\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. pfSense \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0639\u0645\u0627\u0644 \u0642\u0648\u0627\u0646\u06cc\u0646 &hellip;","og_url":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/","og_site_name":"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a","article_published_time":"2025-04-22T04:21:10+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp","type":"image\/webp"}],"author":"\u0627\u062f\u0645\u06cc\u0646","twitter_card":"summary_large_image","twitter_creator":"@acto_bit","twitter_site":"@acto_bit","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637":"\u0627\u062f\u0645\u06cc\u0646","\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647":"13 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#article","isPartOf":{"@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/"},"author":{"name":"\u0627\u062f\u0645\u06cc\u0646","@id":"https:\/\/actobit.com\/actomag\/#\/schema\/person\/373a1606772afbdbc09b93f7b2e5a95e"},"headline":"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc","datePublished":"2025-04-22T04:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/"},"wordCount":228,"commentCount":0,"publisher":{"@id":"https:\/\/actobit.com\/actomag\/#organization"},"image":{"@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage"},"thumbnailUrl":"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp","articleSection":["\u062f\u0627\u0646\u0634\u0646\u0627\u0645\u0647","\u062f\u0648\u0627\u067e\u0633","\u0633\u0627\u06cc\u0631"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/","url":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/","name":"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc","isPartOf":{"@id":"https:\/\/actobit.com\/actomag\/#website"},"primaryImageOfPage":{"@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage"},"image":{"@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage"},"thumbnailUrl":"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp","datePublished":"2025-04-22T04:21:10+00:00","breadcrumb":{"@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#primaryimage","url":"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp","contentUrl":"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2025\/04\/haproxy-as-a-reverse-proxy-on-pfsense-1.webp","width":1200,"height":800,"caption":"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc"},{"@type":"BreadcrumbList","@id":"https:\/\/actobit.com\/actomag\/1404\/haproxy-as-a-reverse-proxy-on-pfsense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/actobit.com\/actomag\/"},{"@type":"ListItem","position":2,"name":"\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc HAProxy \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 Reverse Proxy \u062f\u0631 \u0641\u0627\u06cc\u0631\u0648\u0627\u0644 pfSense \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc"}]},{"@type":"WebSite","@id":"https:\/\/actobit.com\/actomag\/#website","url":"https:\/\/actobit.com\/actomag\/","name":"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a","description":"\u0628\u0644\u0627\u06af \u062c\u0627\u0645\u0639 \u0627\u06a9\u062a\u0648\u0628\u06cc\u062a","publisher":{"@id":"https:\/\/actobit.com\/actomag\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actobit.com\/actomag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/actobit.com\/actomag\/#organization","name":"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a","url":"https:\/\/actobit.com\/actomag\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/actobit.com\/actomag\/#\/schema\/logo\/image\/","url":"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2020\/06\/actomag.png","contentUrl":"https:\/\/actobit.com\/actomag\/wp-content\/uploads\/2020\/06\/actomag.png","width":599,"height":98,"caption":"\u0627\u06a9\u062a\u0648\u0628\u06cc\u062a"},"image":{"@id":"https:\/\/actobit.com\/actomag\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/acto_bit","https:\/\/www.instagram.com\/actobit\/","https:\/\/www.linkedin.com\/in\/actobit"]},{"@type":"Person","@id":"https:\/\/actobit.com\/actomag\/#\/schema\/person\/373a1606772afbdbc09b93f7b2e5a95e","name":"\u0627\u062f\u0645\u06cc\u0646","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/actobit.com\/actomag\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e4c0c194c66063a6885612821c9056cb334a69e1c297cb9de1e0ae7c23ba45fd?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4c0c194c66063a6885612821c9056cb334a69e1c297cb9de1e0ae7c23ba45fd?s=96&d=wavatar&r=g","caption":"\u0627\u062f\u0645\u06cc\u0646"}}]}},"_links":{"self":[{"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/posts\/6628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/users\/1417"}],"replies":[{"embeddable":true,"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/comments?post=6628"}],"version-history":[{"count":4,"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/posts\/6628\/revisions"}],"predecessor-version":[{"id":6633,"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/posts\/6628\/revisions\/6633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/media\/6629"}],"wp:attachment":[{"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/media?parent=6628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/categories?post=6628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actobit.com\/actomag\/wp-json\/wp\/v2\/tags?post=6628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}